{"id":13895,"date":"2018-09-24T18:10:48","date_gmt":"2018-09-24T18:10:48","guid":{"rendered":"http:\/\/nosolocomics.com\/?p=13895"},"modified":"2022-01-02T18:30:40","modified_gmt":"2022-01-02T18:30:40","slug":"el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues","status":"publish","type":"post","link":"https:\/\/www.nosolocomics.com\/blog\/general\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\/","title":{"rendered":"El nuevo Joker de Joaquin Phoenix va a marcar un antes y un despu\u00e9s"},"content":{"rendered":"\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-top\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;13895&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 votos)&quot;,&quot;size&quot;:&quot;22&quot;,&quot;title&quot;:&quot;El nuevo Joker de Joaquin Phoenix va a marcar un antes y un despu\u00e9s&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 17.6px;\">\n            <span class=\"kksr-muted\">Rate this post<\/span>\n    <\/div>\n    <\/div>\n\n<p>Esperad\u00edsimas las primeras im\u00e1genes del Joker de <a href=\"https:\/\/es.wikipedia.org\/wiki\/Joaquin_Phoenix\"><strong>Joaquin Phoenix<\/strong> <\/a>desde que se confirm\u00f3 que el magn\u00edfico actor encarnar\u00eda al famoso icono del crimen en el universo Batman.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"http:\/\/nosolocomics.com\/blog\/wp-content\/uploads\/2018\/09\/joker.jpg\" alt=\"\" class=\"wp-image-13896\"\/><\/figure>\n\n\n\n<p>Ahora se han compartido las primeras im\u00e1genes de las pruebas de c\u00e1mara y no decepciona, ya lo sab\u00edamos cuando vimos a Joaquin Phoenix, actor que ya de por s\u00ed tiene una expresividad fuera de lo com\u00fan y que apunta como un fant\u00e1stico Joker.<\/p>\n\n\n\n<figure class=\"wp-block-embed-instagram wp-block-embed is-type-rich is-provider-gestor-del-servicio\">\nhttps:\/\/www.instagram.com\/p\/Bn_uihPAVhL\/?utm_source=ig_embed\n<\/figure>\n\n\n\n<p>La pel\u00edcula Joker del director <a href=\"https:\/\/es.wikipedia.org\/wiki\/Todd_Phillips\"><strong>Todd Philips<\/strong> <\/a>se estrenar\u00e1 en octubre de 2019 y nos mostrar\u00e1 como Arthur Peck, un monologuista poco afortunado que vuelve a Gotham para cuidar de su madre enferma, se convierte en uno de los mayores criminales de la ciudad y principal antagonista de Batman.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"blob:http:\/\/nosolocomics.com\/ce4bcc37-e34f-483a-ba32-8718dcd7e847\" alt=\"\"\/><figcaption>Los Joker antiguos y Joaquin Ohoenix sin caracterizar<\/figcaption><\/figure>\n\n\n\n<p>La sinopsis oficial:<\/p>\n\n\n\n<p><em>\u00abEn &#8216;The Joker&#8217; exploraremos la vida de un hombre despreciado por la sociedad, donde no es s\u00f3lo trataremos de adentraros en su car\u00e1cter energ\u00e9tico, sino tambi\u00e9n de contar una historia m\u00e1s amplia.\u00bb<\/em><\/p>\n\n\n\n<p>Le\u00eddo en <a href=\"https:\/\/elpais.com\/elpais\/2018\/09\/23\/icon\/1537697370_834596.html\">el pais<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esperad\u00edsimas las primeras im\u00e1genes del Joker de Joaquin Phoenix desde que se confirm\u00f3 que el magn\u00edfico actor encarnar\u00eda al famoso icono del crimen en el universo Batman. Ahora se han compartido las primeras im\u00e1genes de las pruebas de c\u00e1mara y no decepciona, ya lo sab\u00edamos cuando vimos a Joaquin Phoenix, actor que ya de por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13898,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-13895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Esperad\u00edsimas las primeras im\u00e1genes del Joker de Joaquin Phoenix desde que se confirm\u00f3 que el magn\u00edfico actor encarnar\u00eda al famoso icono del crimen en el universo Batman. Ahora se han compartido las primeras im\u00e1genes de las pruebas de c\u00e1mara y no decepciona, ya lo sab\u00edamos cuando vimos a Joaquin Phoenix, actor que ya de por\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"nosolocomics\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.nosolocomics.com\/blog\/general\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Nosolocomics - Tu web para estar informado de lo \u00faltimo y no tan \u00faltimo en el mundo del cine, literatura, c\u00f3mics y merchandising en los g\u00e9neros fant\u00e1stico y ciencia ficci\u00f3n\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El nuevo Joker de Joaquin Phoenix va a marcar un antes y un despu\u00e9s - Nosolocomics\" \/>\n\t\t<meta property=\"og:description\" content=\"Esperad\u00edsimas las primeras im\u00e1genes del Joker de Joaquin Phoenix desde que se confirm\u00f3 que el magn\u00edfico actor encarnar\u00eda al famoso icono del crimen en el universo Batman. Ahora se han compartido las primeras im\u00e1genes de las pruebas de c\u00e1mara y no decepciona, ya lo sab\u00edamos cuando vimos a Joaquin Phoenix, actor que ya de por\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.nosolocomics.com\/blog\/general\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-09-24T18:10:48+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-01-02T18:30:40+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/nosolocomics\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@nosolocomics\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El nuevo Joker de Joaquin Phoenix va a marcar un antes y un despu\u00e9s - Nosolocomics\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Esperad\u00edsimas las primeras im\u00e1genes del Joker de Joaquin Phoenix desde que se confirm\u00f3 que el magn\u00edfico actor encarnar\u00eda al famoso icono del crimen en el universo Batman. Ahora se han compartido las primeras im\u00e1genes de las pruebas de c\u00e1mara y no decepciona, ya lo sab\u00edamos cuando vimos a Joaquin Phoenix, actor que ya de por\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nosolocomics\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/general\\\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\\\/#blogposting\",\"name\":\"El nuevo Joker de Joaquin Phoenix va a marcar un antes y un despu\\u00e9s - Nosolocomics\",\"headline\":\"El nuevo Joker de Joaquin Phoenix va a marcar un antes y un despu\\u00e9s\",\"author\":{\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":13898},\"datePublished\":\"2018-09-24T18:10:48+02:00\",\"dateModified\":\"2022-01-02T18:30:40+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/general\\\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/general\\\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\\\/#webpage\"},\"articleSection\":\"General\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/general\\\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/category\\\/general\\\/#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/category\\\/general\\\/#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/category\\\/general\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/general\\\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\\\/#listItem\",\"name\":\"El nuevo Joker de Joaquin Phoenix va a marcar un antes y un despu\\u00e9s\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/general\\\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\\\/#listItem\",\"position\":3,\"name\":\"El nuevo Joker de Joaquin Phoenix va a marcar un antes y un despu\\u00e9s\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/category\\\/general\\\/#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/#organization\",\"name\":\"Nosolocomics\",\"description\":\"Tu web para estar informado de lo \\u00faltimo y no tan \\u00faltimo en el mundo del cine, literatura, c\\u00f3mics y merchandising en los g\\u00e9neros fant\\u00e1stico y ciencia ficci\\u00f3n\",\"url\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/\",\"email\":\"nosolocomics@gmail.com\",\"foundingDate\":\"2013-10-22\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/NosolocomicsLogoShowcardBlack-Cuadrado.png\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/general\\\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\\\/#organizationLogo\",\"width\":727,\"height\":614},\"image\":{\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/general\\\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/nosolocomics\",\"https:\\\/\\\/x.com\\\/nosolocomics\",\"https:\\\/\\\/instagram.com\\\/nosolocomics\",\"https:\\\/\\\/pinterest.com\\\/nosolocomics\",\"https:\\\/\\\/youtube.com\\\/nosolocomics\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/author\\\/admin\\\/\",\"name\":\"nosolocomics\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/general\\\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/40d54b4069956f43d2842a80d6dbe3fac4e8334f010b4e8449fcf188d66f2ea8?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"nosolocomics\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/general\\\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\\\/#webpage\",\"url\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/general\\\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\\\/\",\"name\":\"El nuevo Joker de Joaquin Phoenix va a marcar un antes y un despu\\u00e9s - Nosolocomics\",\"description\":\"Esperad\\u00edsimas las primeras im\\u00e1genes del Joker de Joaquin Phoenix desde que se confirm\\u00f3 que el magn\\u00edfico actor encarnar\\u00eda al famoso icono del crimen en el universo Batman. Ahora se han compartido las primeras im\\u00e1genes de las pruebas de c\\u00e1mara y no decepciona, ya lo sab\\u00edamos cuando vimos a Joaquin Phoenix, actor que ya de por\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/general\\\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":13898,\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/general\\\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/general\\\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\\\/#mainImage\"},\"datePublished\":\"2018-09-24T18:10:48+02:00\",\"dateModified\":\"2022-01-02T18:30:40+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/\",\"name\":\"Nosolocomics\",\"alternateName\":\"Nosolocomics\",\"description\":\"Tu web para estar informado de lo \\u00faltimo y no tan \\u00faltimo en el mundo del cine, literatura, c\\u00f3mics y merchandising en los g\\u00e9neros fant\\u00e1stico y ciencia ficci\\u00f3n\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El nuevo Joker de Joaquin Phoenix va a marcar un antes y un despu\u00e9s - Nosolocomics","description":"Esperad\u00edsimas las primeras im\u00e1genes del Joker de Joaquin Phoenix desde que se confirm\u00f3 que el magn\u00edfico actor encarnar\u00eda al famoso icono del crimen en el universo Batman. Ahora se han compartido las primeras im\u00e1genes de las pruebas de c\u00e1mara y no decepciona, ya lo sab\u00edamos cuando vimos a Joaquin Phoenix, actor que ya de por","canonical_url":"https:\/\/www.nosolocomics.com\/blog\/general\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.nosolocomics.com\/blog\/general\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\/#blogposting","name":"El nuevo Joker de Joaquin Phoenix va a marcar un antes y un despu\u00e9s - Nosolocomics","headline":"El nuevo Joker de Joaquin Phoenix va a marcar un antes y un despu\u00e9s","author":{"@id":"https:\/\/www.nosolocomics.com\/blog\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.nosolocomics.com\/blog\/#organization"},"image":{"@type":"ImageObject","url":13898},"datePublished":"2018-09-24T18:10:48+02:00","dateModified":"2022-01-02T18:30:40+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.nosolocomics.com\/blog\/general\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\/#webpage"},"isPartOf":{"@id":"https:\/\/www.nosolocomics.com\/blog\/general\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\/#webpage"},"articleSection":"General"},{"@type":"BreadcrumbList","@id":"https:\/\/www.nosolocomics.com\/blog\/general\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.nosolocomics.com\/blog#listItem","position":1,"name":"Home","item":"https:\/\/www.nosolocomics.com\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.nosolocomics.com\/blog\/category\/general\/#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.nosolocomics.com\/blog\/category\/general\/#listItem","position":2,"name":"General","item":"https:\/\/www.nosolocomics.com\/blog\/category\/general\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.nosolocomics.com\/blog\/general\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\/#listItem","name":"El nuevo Joker de Joaquin Phoenix va a marcar un antes y un despu\u00e9s"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.nosolocomics.com\/blog#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.nosolocomics.com\/blog\/general\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\/#listItem","position":3,"name":"El nuevo Joker de Joaquin Phoenix va a marcar un antes y un despu\u00e9s","previousItem":{"@type":"ListItem","@id":"https:\/\/www.nosolocomics.com\/blog\/category\/general\/#listItem","name":"General"}}]},{"@type":"Organization","@id":"https:\/\/www.nosolocomics.com\/blog\/#organization","name":"Nosolocomics","description":"Tu web para estar informado de lo \u00faltimo y no tan \u00faltimo en el mundo del cine, literatura, c\u00f3mics y merchandising en los g\u00e9neros fant\u00e1stico y ciencia ficci\u00f3n","url":"https:\/\/www.nosolocomics.com\/blog\/","email":"nosolocomics@gmail.com","foundingDate":"2013-10-22","logo":{"@type":"ImageObject","url":"https:\/\/www.nosolocomics.com\/blog\/wp-content\/uploads\/2013\/10\/NosolocomicsLogoShowcardBlack-Cuadrado.png","@id":"https:\/\/www.nosolocomics.com\/blog\/general\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\/#organizationLogo","width":727,"height":614},"image":{"@id":"https:\/\/www.nosolocomics.com\/blog\/general\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/nosolocomics","https:\/\/x.com\/nosolocomics","https:\/\/instagram.com\/nosolocomics","https:\/\/pinterest.com\/nosolocomics","https:\/\/youtube.com\/nosolocomics"]},{"@type":"Person","@id":"https:\/\/www.nosolocomics.com\/blog\/author\/admin\/#author","url":"https:\/\/www.nosolocomics.com\/blog\/author\/admin\/","name":"nosolocomics","image":{"@type":"ImageObject","@id":"https:\/\/www.nosolocomics.com\/blog\/general\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/40d54b4069956f43d2842a80d6dbe3fac4e8334f010b4e8449fcf188d66f2ea8?s=96&d=mm&r=g","width":96,"height":96,"caption":"nosolocomics"}},{"@type":"WebPage","@id":"https:\/\/www.nosolocomics.com\/blog\/general\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\/#webpage","url":"https:\/\/www.nosolocomics.com\/blog\/general\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\/","name":"El nuevo Joker de Joaquin Phoenix va a marcar un antes y un despu\u00e9s - Nosolocomics","description":"Esperad\u00edsimas las primeras im\u00e1genes del Joker de Joaquin Phoenix desde que se confirm\u00f3 que el magn\u00edfico actor encarnar\u00eda al famoso icono del crimen en el universo Batman. Ahora se han compartido las primeras im\u00e1genes de las pruebas de c\u00e1mara y no decepciona, ya lo sab\u00edamos cuando vimos a Joaquin Phoenix, actor que ya de por","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.nosolocomics.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.nosolocomics.com\/blog\/general\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\/#breadcrumblist"},"author":{"@id":"https:\/\/www.nosolocomics.com\/blog\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.nosolocomics.com\/blog\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":13898,"@id":"https:\/\/www.nosolocomics.com\/blog\/general\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.nosolocomics.com\/blog\/general\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\/#mainImage"},"datePublished":"2018-09-24T18:10:48+02:00","dateModified":"2022-01-02T18:30:40+02:00"},{"@type":"WebSite","@id":"https:\/\/www.nosolocomics.com\/blog\/#website","url":"https:\/\/www.nosolocomics.com\/blog\/","name":"Nosolocomics","alternateName":"Nosolocomics","description":"Tu web para estar informado de lo \u00faltimo y no tan \u00faltimo en el mundo del cine, literatura, c\u00f3mics y merchandising en los g\u00e9neros fant\u00e1stico y ciencia ficci\u00f3n","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.nosolocomics.com\/blog\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Nosolocomics - Tu web para estar informado de lo \u00faltimo y no tan \u00faltimo en el mundo del cine, literatura, c\u00f3mics y merchandising en los g\u00e9neros fant\u00e1stico y ciencia ficci\u00f3n","og:type":"article","og:title":"El nuevo Joker de Joaquin Phoenix va a marcar un antes y un despu\u00e9s - Nosolocomics","og:description":"Esperad\u00edsimas las primeras im\u00e1genes del Joker de Joaquin Phoenix desde que se confirm\u00f3 que el magn\u00edfico actor encarnar\u00eda al famoso icono del crimen en el universo Batman. Ahora se han compartido las primeras im\u00e1genes de las pruebas de c\u00e1mara y no decepciona, ya lo sab\u00edamos cuando vimos a Joaquin Phoenix, actor que ya de por","og:url":"https:\/\/www.nosolocomics.com\/blog\/general\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\/","article:published_time":"2018-09-24T18:10:48+00:00","article:modified_time":"2022-01-02T18:30:40+00:00","article:publisher":"https:\/\/facebook.com\/nosolocomics","twitter:card":"summary_large_image","twitter:site":"@nosolocomics","twitter:title":"El nuevo Joker de Joaquin Phoenix va a marcar un antes y un despu\u00e9s - Nosolocomics","twitter:description":"Esperad\u00edsimas las primeras im\u00e1genes del Joker de Joaquin Phoenix desde que se confirm\u00f3 que el magn\u00edfico actor encarnar\u00eda al famoso icono del crimen en el universo Batman. Ahora se han compartido las primeras im\u00e1genes de las pruebas de c\u00e1mara y no decepciona, ya lo sab\u00edamos cuando vimos a Joaquin Phoenix, actor que ya de por","twitter:creator":"@nosolocomics"},"aioseo_meta_data":{"post_id":"13895","title":null,"description":null,"keywords":null,"keyphrases":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-09-18 12:50:34","updated":"2025-08-02 09:12:58","primary_term":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.nosolocomics.com\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.nosolocomics.com\/blog\/category\/general\/\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEl nuevo Joker de Joaquin Phoenix va a marcar un antes y un despu\u00e9s\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.nosolocomics.com\/blog"},{"label":"General","link":"https:\/\/www.nosolocomics.com\/blog\/category\/general\/"},{"label":"El nuevo Joker de Joaquin Phoenix va a marcar un antes y un despu\u00e9s","link":"https:\/\/www.nosolocomics.com\/blog\/general\/el-nuevo-joker-de-joaquin-phoenix-va-a-marcar-un-antes-y-un-despues\/"}],"_links":{"self":[{"href":"https:\/\/www.nosolocomics.com\/blog\/wp-json\/wp\/v2\/posts\/13895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nosolocomics.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nosolocomics.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nosolocomics.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nosolocomics.com\/blog\/wp-json\/wp\/v2\/comments?post=13895"}],"version-history":[{"count":1,"href":"https:\/\/www.nosolocomics.com\/blog\/wp-json\/wp\/v2\/posts\/13895\/revisions"}],"predecessor-version":[{"id":23087,"href":"https:\/\/www.nosolocomics.com\/blog\/wp-json\/wp\/v2\/posts\/13895\/revisions\/23087"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nosolocomics.com\/blog\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.nosolocomics.com\/blog\/wp-json\/wp\/v2\/media?parent=13895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nosolocomics.com\/blog\/wp-json\/wp\/v2\/categories?post=13895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nosolocomics.com\/blog\/wp-json\/wp\/v2\/tags?post=13895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}