{"id":23823,"date":"2022-09-18T10:28:16","date_gmt":"2022-09-18T10:28:16","guid":{"rendered":"http:\/\/www.nosolocomics.com\/blog\/?p=23823"},"modified":"2022-09-18T10:28:17","modified_gmt":"2022-09-18T10:28:17","slug":"y-tendremos-serie-de-blade-runner","status":"publish","type":"post","link":"https:\/\/www.nosolocomics.com\/blog\/seriespeliculas\/y-tendremos-serie-de-blade-runner\/","title":{"rendered":"Y tendremos serie de Blade Runner&#8230;"},"content":{"rendered":"\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-top\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;23823&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 votos)&quot;,&quot;size&quot;:&quot;22&quot;,&quot;title&quot;:&quot;Y tendremos serie de Blade Runner...&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 17.6px;\">\n            <span class=\"kksr-muted\">Rate this post<\/span>\n    <\/div>\n    <\/div>\n\n<p>Pues s\u00ed, en esta \u00e9poca de abundancia de series, todas las fuentes son buenas y m\u00e1s si parten de una de las atm\u00f3sferas m\u00e1s atractivas en la ciencia ficci\u00f3n.<\/p>\n\n\n\n<p>Y es que desde la m\u00edtica pel\u00edcula de <strong><a href=\"https:\/\/es.wikipedia.org\/wiki\/Ridley_Scott\">Ridley Scott <\/a><\/strong>en los 80, Blade Runner siempre ha tenido algo de legendario, tanto que su secuela cinematogr\u00e1fica se hizo esperar hasta que Denis Villeneuve nos ofreci\u00f3 su muy meritoria versi\u00f3n en <a href=\"http:\/\/www.nosolocomics.com\/blog\/seriespeliculas\/ahora-nuevo-trailer-blade-runner-2049-lo-estabamos-esperando\/\" data-type=\"post\" data-id=\"13640\">Bladerunner<\/a> 2049, all\u00e1 por el 2017&#8230;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"688\" height=\"1024\" src=\"http:\/\/www.nosolocomics.com\/blog\/wp-content\/uploads\/2022\/09\/image-688x1024.png\" alt=\"\" class=\"wp-image-23824\" srcset=\"https:\/\/www.nosolocomics.com\/blog\/wp-content\/uploads\/2022\/09\/image-688x1024.png 688w, https:\/\/www.nosolocomics.com\/blog\/wp-content\/uploads\/2022\/09\/image-202x300.png 202w, https:\/\/www.nosolocomics.com\/blog\/wp-content\/uploads\/2022\/09\/image-768x1143.png 768w, https:\/\/www.nosolocomics.com\/blog\/wp-content\/uploads\/2022\/09\/image-1032x1536.png 1032w, https:\/\/www.nosolocomics.com\/blog\/wp-content\/uploads\/2022\/09\/image-1376x2048.png 1376w\" sizes=\"auto, (max-width: 688px) 100vw, 688px\" \/><figcaption>La original que lo cre\u00f3 todo<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"691\" height=\"1024\" src=\"http:\/\/www.nosolocomics.com\/blog\/wp-content\/uploads\/2022\/09\/image-1-691x1024.png\" alt=\"\" class=\"wp-image-23825\" srcset=\"https:\/\/www.nosolocomics.com\/blog\/wp-content\/uploads\/2022\/09\/image-1-691x1024.png 691w, https:\/\/www.nosolocomics.com\/blog\/wp-content\/uploads\/2022\/09\/image-1-202x300.png 202w, https:\/\/www.nosolocomics.com\/blog\/wp-content\/uploads\/2022\/09\/image-1-768x1138.png 768w, https:\/\/www.nosolocomics.com\/blog\/wp-content\/uploads\/2022\/09\/image-1-1037x1536.png 1037w, https:\/\/www.nosolocomics.com\/blog\/wp-content\/uploads\/2022\/09\/image-1.png 1382w\" sizes=\"auto, (max-width: 691px) 100vw, 691px\" \/><figcaption>Y la revisitaci\u00f3n<\/figcaption><\/figure>\n\n\n\n<p>Ahora nos llegar\u00e1 <strong>Blade Runner 2099<\/strong>, serie que producir\u00e1 el mismo <strong>Ridley Scott <\/strong>de la mano de la producci\u00f3n de un <strong>Amazon Studios <\/strong>que parece tiene mucho dinero por gastar y eso es bueno, como ya hemos visto en la <a href=\"http:\/\/www.nosolocomics.com\/blog\/general\/el-senor-de-los-anillos-sera-producido-por-juan-antonio-bayona\/\" data-type=\"post\" data-id=\"14128\">nueva serie de El se\u00f1or de los anillos<\/a>, donde el ingente presupuesto proporcionado por Amazon nos ha legado una gran serie que no escatima en detalles para reproducir el fant\u00e1stico mundo de Tolkien (pol\u00e9micas por su fidelidad aparte, por supuesto)&#8230;<\/p>\n\n\n\n<p>Poco sabemos m\u00e1s all\u00e1 de que ser\u00e1 cierta relaci\u00f3n con el argumento de la \u00faltima pel\u00edcula ambientada en el a\u00f1o 2049 y que inicialmente constar\u00eda de 10 episodios, siendo un proyecto prioritario y que no tardar\u00eda demasiado en aparecer&#8230; Estaremos atentos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"http:\/\/www.nosolocomics.com\/blog\/wp-content\/uploads\/2022\/09\/image-2-1024x576.png\" alt=\"\" class=\"wp-image-23826\" srcset=\"https:\/\/www.nosolocomics.com\/blog\/wp-content\/uploads\/2022\/09\/image-2-1024x576.png 1024w, https:\/\/www.nosolocomics.com\/blog\/wp-content\/uploads\/2022\/09\/image-2-300x169.png 300w, https:\/\/www.nosolocomics.com\/blog\/wp-content\/uploads\/2022\/09\/image-2-768x432.png 768w, https:\/\/www.nosolocomics.com\/blog\/wp-content\/uploads\/2022\/09\/image-2-1536x864.png 1536w, https:\/\/www.nosolocomics.com\/blog\/wp-content\/uploads\/2022\/09\/image-2.png 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Pues s\u00ed, en esta \u00e9poca de abundancia de series, todas las fuentes son buenas y m\u00e1s si parten de una de las atm\u00f3sferas m\u00e1s atractivas en la ciencia ficci\u00f3n. Y es que desde la m\u00edtica pel\u00edcula de Ridley Scott en los 80, Blade Runner siempre ha tenido algo de legendario, tanto que su secuela cinematogr\u00e1fica [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23826,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8],"tags":[25],"class_list":["post-23823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seriespeliculas","tag-blade-runner"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Pues s\u00ed, en esta \u00e9poca de abundancia de series, todas las fuentes son buenas y m\u00e1s si parten de una de las atm\u00f3sferas m\u00e1s atractivas en la ciencia ficci\u00f3n. Y es que desde la m\u00edtica pel\u00edcula de Ridley Scott en los 80, Blade Runner siempre ha tenido algo de legendario, tanto que su secuela cinematogr\u00e1fica\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"nosolocomics\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.nosolocomics.com\/blog\/seriespeliculas\/y-tendremos-serie-de-blade-runner\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Nosolocomics - Tu web para estar informado de lo \u00faltimo y no tan \u00faltimo en el mundo del cine, literatura, c\u00f3mics y merchandising en los g\u00e9neros fant\u00e1stico y ciencia ficci\u00f3n\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Y tendremos serie de Blade Runner\u2026 - Nosolocomics\" \/>\n\t\t<meta property=\"og:description\" content=\"Pues s\u00ed, en esta \u00e9poca de abundancia de series, todas las fuentes son buenas y m\u00e1s si parten de una de las atm\u00f3sferas m\u00e1s atractivas en la ciencia ficci\u00f3n. Y es que desde la m\u00edtica pel\u00edcula de Ridley Scott en los 80, Blade Runner siempre ha tenido algo de legendario, tanto que su secuela cinematogr\u00e1fica\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.nosolocomics.com\/blog\/seriespeliculas\/y-tendremos-serie-de-blade-runner\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-09-18T10:28:16+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-09-18T10:28:17+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/nosolocomics\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@nosolocomics\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Y tendremos serie de Blade Runner\u2026 - Nosolocomics\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Pues s\u00ed, en esta \u00e9poca de abundancia de series, todas las fuentes son buenas y m\u00e1s si parten de una de las atm\u00f3sferas m\u00e1s atractivas en la ciencia ficci\u00f3n. Y es que desde la m\u00edtica pel\u00edcula de Ridley Scott en los 80, Blade Runner siempre ha tenido algo de legendario, tanto que su secuela cinematogr\u00e1fica\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nosolocomics\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/seriespeliculas\\\/y-tendremos-serie-de-blade-runner\\\/#blogposting\",\"name\":\"Y tendremos serie de Blade Runner\\u2026 - Nosolocomics\",\"headline\":\"Y tendremos serie de Blade Runner&#8230;\",\"author\":{\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/image-2.png\",\"width\":1920,\"height\":1080},\"datePublished\":\"2022-09-18T10:28:16+02:00\",\"dateModified\":\"2022-09-18T10:28:17+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/seriespeliculas\\\/y-tendremos-serie-de-blade-runner\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/seriespeliculas\\\/y-tendremos-serie-de-blade-runner\\\/#webpage\"},\"articleSection\":\"Series y Pel\\u00edculas, Blade Runner\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/seriespeliculas\\\/y-tendremos-serie-de-blade-runner\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/category\\\/seriespeliculas\\\/#listItem\",\"name\":\"Series y Pel\\u00edculas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/category\\\/seriespeliculas\\\/#listItem\",\"position\":2,\"name\":\"Series y Pel\\u00edculas\",\"item\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/category\\\/seriespeliculas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/seriespeliculas\\\/y-tendremos-serie-de-blade-runner\\\/#listItem\",\"name\":\"Y tendremos serie de Blade Runner&#8230;\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/seriespeliculas\\\/y-tendremos-serie-de-blade-runner\\\/#listItem\",\"position\":3,\"name\":\"Y tendremos serie de Blade Runner&#8230;\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/category\\\/seriespeliculas\\\/#listItem\",\"name\":\"Series y Pel\\u00edculas\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/#organization\",\"name\":\"Nosolocomics\",\"description\":\"Tu web para estar informado de lo \\u00faltimo y no tan \\u00faltimo en el mundo del cine, literatura, c\\u00f3mics y merchandising en los g\\u00e9neros fant\\u00e1stico y ciencia ficci\\u00f3n\",\"url\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/\",\"email\":\"nosolocomics@gmail.com\",\"foundingDate\":\"2013-10-22\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/NosolocomicsLogoShowcardBlack-Cuadrado.png\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/seriespeliculas\\\/y-tendremos-serie-de-blade-runner\\\/#organizationLogo\",\"width\":727,\"height\":614},\"image\":{\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/seriespeliculas\\\/y-tendremos-serie-de-blade-runner\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/nosolocomics\",\"https:\\\/\\\/x.com\\\/nosolocomics\",\"https:\\\/\\\/instagram.com\\\/nosolocomics\",\"https:\\\/\\\/pinterest.com\\\/nosolocomics\",\"https:\\\/\\\/youtube.com\\\/nosolocomics\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/author\\\/admin\\\/\",\"name\":\"nosolocomics\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/seriespeliculas\\\/y-tendremos-serie-de-blade-runner\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/40d54b4069956f43d2842a80d6dbe3fac4e8334f010b4e8449fcf188d66f2ea8?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"nosolocomics\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/seriespeliculas\\\/y-tendremos-serie-de-blade-runner\\\/#webpage\",\"url\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/seriespeliculas\\\/y-tendremos-serie-de-blade-runner\\\/\",\"name\":\"Y tendremos serie de Blade Runner\\u2026 - Nosolocomics\",\"description\":\"Pues s\\u00ed, en esta \\u00e9poca de abundancia de series, todas las fuentes son buenas y m\\u00e1s si parten de una de las atm\\u00f3sferas m\\u00e1s atractivas en la ciencia ficci\\u00f3n. Y es que desde la m\\u00edtica pel\\u00edcula de Ridley Scott en los 80, Blade Runner siempre ha tenido algo de legendario, tanto que su secuela cinematogr\\u00e1fica\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/seriespeliculas\\\/y-tendremos-serie-de-blade-runner\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/image-2.png\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/seriespeliculas\\\/y-tendremos-serie-de-blade-runner\\\/#mainImage\",\"width\":1920,\"height\":1080},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/seriespeliculas\\\/y-tendremos-serie-de-blade-runner\\\/#mainImage\"},\"datePublished\":\"2022-09-18T10:28:16+02:00\",\"dateModified\":\"2022-09-18T10:28:17+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/\",\"name\":\"Nosolocomics\",\"alternateName\":\"Nosolocomics\",\"description\":\"Tu web para estar informado de lo \\u00faltimo y no tan \\u00faltimo en el mundo del cine, literatura, c\\u00f3mics y merchandising en los g\\u00e9neros fant\\u00e1stico y ciencia ficci\\u00f3n\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nosolocomics.com\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Y tendremos serie de Blade Runner\u2026 - Nosolocomics","description":"Pues s\u00ed, en esta \u00e9poca de abundancia de series, todas las fuentes son buenas y m\u00e1s si parten de una de las atm\u00f3sferas m\u00e1s atractivas en la ciencia ficci\u00f3n. Y es que desde la m\u00edtica pel\u00edcula de Ridley Scott en los 80, Blade Runner siempre ha tenido algo de legendario, tanto que su secuela cinematogr\u00e1fica","canonical_url":"https:\/\/www.nosolocomics.com\/blog\/seriespeliculas\/y-tendremos-serie-de-blade-runner\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.nosolocomics.com\/blog\/seriespeliculas\/y-tendremos-serie-de-blade-runner\/#blogposting","name":"Y tendremos serie de Blade Runner\u2026 - Nosolocomics","headline":"Y tendremos serie de Blade Runner&#8230;","author":{"@id":"https:\/\/www.nosolocomics.com\/blog\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.nosolocomics.com\/blog\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.nosolocomics.com\/blog\/wp-content\/uploads\/2022\/09\/image-2.png","width":1920,"height":1080},"datePublished":"2022-09-18T10:28:16+02:00","dateModified":"2022-09-18T10:28:17+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.nosolocomics.com\/blog\/seriespeliculas\/y-tendremos-serie-de-blade-runner\/#webpage"},"isPartOf":{"@id":"https:\/\/www.nosolocomics.com\/blog\/seriespeliculas\/y-tendremos-serie-de-blade-runner\/#webpage"},"articleSection":"Series y Pel\u00edculas, Blade Runner"},{"@type":"BreadcrumbList","@id":"https:\/\/www.nosolocomics.com\/blog\/seriespeliculas\/y-tendremos-serie-de-blade-runner\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.nosolocomics.com\/blog#listItem","position":1,"name":"Home","item":"https:\/\/www.nosolocomics.com\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.nosolocomics.com\/blog\/category\/seriespeliculas\/#listItem","name":"Series y Pel\u00edculas"}},{"@type":"ListItem","@id":"https:\/\/www.nosolocomics.com\/blog\/category\/seriespeliculas\/#listItem","position":2,"name":"Series y Pel\u00edculas","item":"https:\/\/www.nosolocomics.com\/blog\/category\/seriespeliculas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.nosolocomics.com\/blog\/seriespeliculas\/y-tendremos-serie-de-blade-runner\/#listItem","name":"Y tendremos serie de Blade Runner&#8230;"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.nosolocomics.com\/blog#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.nosolocomics.com\/blog\/seriespeliculas\/y-tendremos-serie-de-blade-runner\/#listItem","position":3,"name":"Y tendremos serie de Blade Runner&#8230;","previousItem":{"@type":"ListItem","@id":"https:\/\/www.nosolocomics.com\/blog\/category\/seriespeliculas\/#listItem","name":"Series y Pel\u00edculas"}}]},{"@type":"Organization","@id":"https:\/\/www.nosolocomics.com\/blog\/#organization","name":"Nosolocomics","description":"Tu web para estar informado de lo \u00faltimo y no tan \u00faltimo en el mundo del cine, literatura, c\u00f3mics y merchandising en los g\u00e9neros fant\u00e1stico y ciencia ficci\u00f3n","url":"https:\/\/www.nosolocomics.com\/blog\/","email":"nosolocomics@gmail.com","foundingDate":"2013-10-22","logo":{"@type":"ImageObject","url":"https:\/\/www.nosolocomics.com\/blog\/wp-content\/uploads\/2013\/10\/NosolocomicsLogoShowcardBlack-Cuadrado.png","@id":"https:\/\/www.nosolocomics.com\/blog\/seriespeliculas\/y-tendremos-serie-de-blade-runner\/#organizationLogo","width":727,"height":614},"image":{"@id":"https:\/\/www.nosolocomics.com\/blog\/seriespeliculas\/y-tendremos-serie-de-blade-runner\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/nosolocomics","https:\/\/x.com\/nosolocomics","https:\/\/instagram.com\/nosolocomics","https:\/\/pinterest.com\/nosolocomics","https:\/\/youtube.com\/nosolocomics"]},{"@type":"Person","@id":"https:\/\/www.nosolocomics.com\/blog\/author\/admin\/#author","url":"https:\/\/www.nosolocomics.com\/blog\/author\/admin\/","name":"nosolocomics","image":{"@type":"ImageObject","@id":"https:\/\/www.nosolocomics.com\/blog\/seriespeliculas\/y-tendremos-serie-de-blade-runner\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/40d54b4069956f43d2842a80d6dbe3fac4e8334f010b4e8449fcf188d66f2ea8?s=96&d=mm&r=g","width":96,"height":96,"caption":"nosolocomics"}},{"@type":"WebPage","@id":"https:\/\/www.nosolocomics.com\/blog\/seriespeliculas\/y-tendremos-serie-de-blade-runner\/#webpage","url":"https:\/\/www.nosolocomics.com\/blog\/seriespeliculas\/y-tendremos-serie-de-blade-runner\/","name":"Y tendremos serie de Blade Runner\u2026 - Nosolocomics","description":"Pues s\u00ed, en esta \u00e9poca de abundancia de series, todas las fuentes son buenas y m\u00e1s si parten de una de las atm\u00f3sferas m\u00e1s atractivas en la ciencia ficci\u00f3n. Y es que desde la m\u00edtica pel\u00edcula de Ridley Scott en los 80, Blade Runner siempre ha tenido algo de legendario, tanto que su secuela cinematogr\u00e1fica","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.nosolocomics.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.nosolocomics.com\/blog\/seriespeliculas\/y-tendremos-serie-de-blade-runner\/#breadcrumblist"},"author":{"@id":"https:\/\/www.nosolocomics.com\/blog\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.nosolocomics.com\/blog\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.nosolocomics.com\/blog\/wp-content\/uploads\/2022\/09\/image-2.png","@id":"https:\/\/www.nosolocomics.com\/blog\/seriespeliculas\/y-tendremos-serie-de-blade-runner\/#mainImage","width":1920,"height":1080},"primaryImageOfPage":{"@id":"https:\/\/www.nosolocomics.com\/blog\/seriespeliculas\/y-tendremos-serie-de-blade-runner\/#mainImage"},"datePublished":"2022-09-18T10:28:16+02:00","dateModified":"2022-09-18T10:28:17+02:00"},{"@type":"WebSite","@id":"https:\/\/www.nosolocomics.com\/blog\/#website","url":"https:\/\/www.nosolocomics.com\/blog\/","name":"Nosolocomics","alternateName":"Nosolocomics","description":"Tu web para estar informado de lo \u00faltimo y no tan \u00faltimo en el mundo del cine, literatura, c\u00f3mics y merchandising en los g\u00e9neros fant\u00e1stico y ciencia ficci\u00f3n","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.nosolocomics.com\/blog\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Nosolocomics - Tu web para estar informado de lo \u00faltimo y no tan \u00faltimo en el mundo del cine, literatura, c\u00f3mics y merchandising en los g\u00e9neros fant\u00e1stico y ciencia ficci\u00f3n","og:type":"article","og:title":"Y tendremos serie de Blade Runner\u2026 - Nosolocomics","og:description":"Pues s\u00ed, en esta \u00e9poca de abundancia de series, todas las fuentes son buenas y m\u00e1s si parten de una de las atm\u00f3sferas m\u00e1s atractivas en la ciencia ficci\u00f3n. Y es que desde la m\u00edtica pel\u00edcula de Ridley Scott en los 80, Blade Runner siempre ha tenido algo de legendario, tanto que su secuela cinematogr\u00e1fica","og:url":"https:\/\/www.nosolocomics.com\/blog\/seriespeliculas\/y-tendremos-serie-de-blade-runner\/","article:published_time":"2022-09-18T10:28:16+00:00","article:modified_time":"2022-09-18T10:28:17+00:00","article:publisher":"https:\/\/facebook.com\/nosolocomics","twitter:card":"summary_large_image","twitter:site":"@nosolocomics","twitter:title":"Y tendremos serie de Blade Runner\u2026 - Nosolocomics","twitter:description":"Pues s\u00ed, en esta \u00e9poca de abundancia de series, todas las fuentes son buenas y m\u00e1s si parten de una de las atm\u00f3sferas m\u00e1s atractivas en la ciencia ficci\u00f3n. Y es que desde la m\u00edtica pel\u00edcula de Ridley Scott en los 80, Blade Runner siempre ha tenido algo de legendario, tanto que su secuela cinematogr\u00e1fica","twitter:creator":"@nosolocomics"},"aioseo_meta_data":{"post_id":"23823","title":null,"description":null,"keywords":null,"keyphrases":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-09-18 13:06:43","updated":"2025-08-02 09:16:50","primary_term":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.nosolocomics.com\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.nosolocomics.com\/blog\/category\/seriespeliculas\/\" title=\"Series y Pel\u00edculas\">Series y Pel\u00edculas<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tY tendremos serie de Blade Runner\u2026\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.nosolocomics.com\/blog"},{"label":"Series y Pel\u00edculas","link":"https:\/\/www.nosolocomics.com\/blog\/category\/seriespeliculas\/"},{"label":"Y tendremos serie de Blade Runner&#8230;","link":"https:\/\/www.nosolocomics.com\/blog\/seriespeliculas\/y-tendremos-serie-de-blade-runner\/"}],"_links":{"self":[{"href":"https:\/\/www.nosolocomics.com\/blog\/wp-json\/wp\/v2\/posts\/23823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nosolocomics.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nosolocomics.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nosolocomics.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nosolocomics.com\/blog\/wp-json\/wp\/v2\/comments?post=23823"}],"version-history":[{"count":1,"href":"https:\/\/www.nosolocomics.com\/blog\/wp-json\/wp\/v2\/posts\/23823\/revisions"}],"predecessor-version":[{"id":23827,"href":"https:\/\/www.nosolocomics.com\/blog\/wp-json\/wp\/v2\/posts\/23823\/revisions\/23827"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nosolocomics.com\/blog\/wp-json\/wp\/v2\/media\/23826"}],"wp:attachment":[{"href":"https:\/\/www.nosolocomics.com\/blog\/wp-json\/wp\/v2\/media?parent=23823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nosolocomics.com\/blog\/wp-json\/wp\/v2\/categories?post=23823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nosolocomics.com\/blog\/wp-json\/wp\/v2\/tags?post=23823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}